{"id":1644413,"date":"2023-02-26T06:00:00","date_gmt":"2023-02-26T06:00:00","guid":{"rendered":"https:\/\/www.myzen.tv\/?p=1644413"},"modified":"2023-02-22T15:34:06","modified_gmt":"2023-02-22T15:34:06","slug":"5-astuces-pour-booster-son-systeme-immunitaire-naturellement","status":"publish","type":"post","link":"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/","title":{"rendered":"5 astuces pour booster son syst\u00e8me immunitaire naturellement"},"content":{"rendered":"\n<p>C\u2019est la grande question du moment ! Cela para\u00eet \u00eatre une chose impossible, et pourtant, il existe une multitude de petites choses simples et <strong>naturelles<\/strong> \u00e0 faire au quotidien pour <strong>renforcer votre syst\u00e8me immunitaire.<\/strong> <a href=\"https:\/\/www.myzen.tv\/fr\/\">MyZen TV<\/a> vous explique tout.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Manger une orange plut\u00f4t qu&rsquo;un jus<\/h2>\n\n\n\n<p>Vous n\u2019imaginez pas tous les bienfaits que votre corps pourra puiser dans <strong>une orange<\/strong>. <strong>Vitamines B<\/strong>, <strong>potassium<\/strong>, thiamine, <strong>acide amin\u00e9<\/strong>, folates, sucres&#8230; Tout est bon pour vous accorder une bonne dose d\u2019<strong>\u00e9nergie<\/strong> pour toute la journ\u00e9e. <\/p>\n\n\n\n<p>Mais avez-vous remarqu\u00e9 que nous parlons du fruit et non de son jus ? Et pour cause, boire un verre de jus d&rsquo;orange revient exactement \u00e0 boire un grand verre de soda ! En effet, comme votre corps ne m\u00e2che pas l&rsquo;aliment, il ne fait pas la diff\u00e9rence entre le sucre d&rsquo;un soda et le jus d&rsquo;une orange. Alors privil\u00e9giez de manger vos oranges plut\u00f4t que de les boire en jus. Et en plus, c\u2019est d\u00e9licieux ! <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pratiquer une activit\u00e9 physique r\u00e9guli\u00e8re<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"706\" src=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-HHXdPG_eTIQ-unsplash-1024x706.jpg\" alt=\"Faire une activit\u00e9 physique\" class=\"wp-image-1644416\" srcset=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-HHXdPG_eTIQ-unsplash-1024x706.jpg 1024w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-HHXdPG_eTIQ-unsplash-300x207.jpg 300w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-HHXdPG_eTIQ-unsplash-768x530.jpg 768w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-HHXdPG_eTIQ-unsplash-1536x1060.jpg 1536w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-HHXdPG_eTIQ-unsplash-2048x1413.jpg 2048w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-HHXdPG_eTIQ-unsplash-275x190.jpg 275w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-HHXdPG_eTIQ-unsplash-203x140.jpg 203w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Faire une activit\u00e9 physique<\/figcaption><\/figure><\/div>\n\n\n<p>On a tous entendu au moins une fois dans notre vie ce fameux slogan. \u201c<em>Pour votre sant\u00e9, pratiquez une <strong>activit\u00e9 physique r\u00e9guli\u00e8re<\/strong><\/em>.\u201d. Et c\u2019est bien vrai ! Garder la forme vous permettra de consolider votre <strong>syst\u00e8me immunitaire<\/strong>. Mais \u00e9galement d&rsquo;\u00eatre plus apte \u00e0 vous d\u00e9fendre en cas d\u2019attaque ext\u00e9rieure. C\u2019est d\u2019ailleurs ce que pr\u00f4ne <a aria-label=\"la naturopathie (opens in a new tab)\" href=\"https:\/\/www.myzen.tv\/fr\/zoom-sur-la-naturopathie\" target=\"_blank\" rel=\"noreferrer noopener\">la naturopathie<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Faire une cure de magn\u00e9sium&nbsp;<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/etty-fidele-oJpkjWcScyg-unsplash-1024x683.jpg\" alt=\"F\u00e8ve de cacao\" class=\"wp-image-1644418\" srcset=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/etty-fidele-oJpkjWcScyg-unsplash-1024x683.jpg 1024w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/etty-fidele-oJpkjWcScyg-unsplash-300x200.jpg 300w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/etty-fidele-oJpkjWcScyg-unsplash-768x512.jpg 768w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/etty-fidele-oJpkjWcScyg-unsplash-1536x1024.jpg 1536w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/etty-fidele-oJpkjWcScyg-unsplash-2048x1365.jpg 2048w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/etty-fidele-oJpkjWcScyg-unsplash-285x190.jpg 285w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/etty-fidele-oJpkjWcScyg-unsplash-210x140.jpg 210w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>F\u00e8ve de cacao<\/figcaption><\/figure><\/div>\n\n\n<p><strong>Le magn\u00e9sium<\/strong> est le grand alli\u00e9 de vos petits coups de barre. Pr\u00e9sent dans une multitude d\u2019aliments du quotidien, il est tr\u00e8s facile de privil\u00e9gier une alimentation \u00e0 base de magn\u00e9sium. En effet, il <strong>renforce notre syst\u00e8me immunitaire<\/strong>. Vous en trouverez par exemple dans les sardines \u00e0 l\u2019huile, le cacao, le caf\u00e9, le chocolat noir \u00e0 70 % de cacao ou plus. Mais \u00e9galement les amandes et noix de cajou, les fruits de mer, le tofu, et m\u00eame\u2026 Les escargots ! L\u2019ingr\u00e9dient qui gagne la t\u00eate du podium en termes de teneur en magn\u00e9sium est le meloukhia en poudre avec un apport de 162 % pour 100 grammes. Impressionnant ! <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Avoir un bon rythme de sommeil<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-s8PTWCu5maQ-unsplash-1024x683.jpg\" alt=\"Une bonne nuit de sommeil\" class=\"wp-image-1644420\" width=\"840\" height=\"560\" srcset=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-s8PTWCu5maQ-unsplash-1024x683.jpg 1024w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-s8PTWCu5maQ-unsplash-300x200.jpg 300w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-s8PTWCu5maQ-unsplash-768x512.jpg 768w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-s8PTWCu5maQ-unsplash-1536x1024.jpg 1536w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-s8PTWCu5maQ-unsplash-2048x1365.jpg 2048w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-s8PTWCu5maQ-unsplash-285x190.jpg 285w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/bruce-mars-s8PTWCu5maQ-unsplash-210x140.jpg 210w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><figcaption>Une bonne nuit de sommeil<\/figcaption><\/figure><\/div>\n\n\n<p>Pendant la nuit, de nombreux organes du <strong>m\u00e9tabolisme<\/strong> se r\u00e9g\u00e9n\u00e8rent, comme notre foi, nos poumons, nos muscles, et m\u00eame nos neurones ! Avoir un <a href=\"https:\/\/www.myzen.tv\/fr\/5-conseils-pour-mieux-dormir\/\"><strong>rythme de sommeil<\/strong> r\u00e9gulier<\/a> et suffisant est donc primordial pour garder un <strong>syst\u00e8me immunitaire<\/strong> solide. Il para\u00eet que les meilleures heures du sommeil se font avant minuit. Mais ne vous inqui\u00e9tez pas, l&rsquo;important, c&rsquo;est de <a href=\"https:\/\/www.myzen.tv\/fr\/les-bienfaits-du-sommeil\/\">dormir \u00e0 sa convenance<\/a>.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Privil\u00e9gier une alimentation saine<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"777\" src=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/12\/tom-brunberg-D4ZtZX1UeAI-unsplash-2-1024x777.jpg\" alt=\"Fruits et l\u00e9gumes\" class=\"wp-image-1679769\" srcset=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/12\/tom-brunberg-D4ZtZX1UeAI-unsplash-2-1024x777.jpg 1024w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/12\/tom-brunberg-D4ZtZX1UeAI-unsplash-2-300x228.jpg 300w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/12\/tom-brunberg-D4ZtZX1UeAI-unsplash-2-768x583.jpg 768w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/12\/tom-brunberg-D4ZtZX1UeAI-unsplash-2-1536x1165.jpg 1536w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/12\/tom-brunberg-D4ZtZX1UeAI-unsplash-2-2048x1553.jpg 2048w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/12\/tom-brunberg-D4ZtZX1UeAI-unsplash-2-251x190.jpg 251w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/12\/tom-brunberg-D4ZtZX1UeAI-unsplash-2-185x140.jpg 185w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/12\/tom-brunberg-D4ZtZX1UeAI-unsplash-2-468x355.jpg 468w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Fruits et l\u00e9gumes<\/figcaption><\/figure>\n\n\n\n<p>Cela tombe sous le sens, mais lorsqu\u2019il s\u2019agit de l\u2019appliquer, c\u2019est une autre affaire ! <strong>Privil\u00e9giez les fruits et les l\u00e9gumes<\/strong>, l\u00e9gumineuses, c\u00e9r\u00e9ales semi-compl\u00e8tes ou compl\u00e8tes, et tentez d\u2019\u00e9viter les aliments trop gras et trop sucr\u00e9s. Plus facile \u00e0 dire qu&rsquo;\u00e0 faire&#8230; Il vaut mieux pr\u00e9f\u00e9rer les graisses instaur\u00e9es contenant des acides gras essentiels : huile vierge, riche en om\u00e9ga-3, comme l\u2019huile de noix, de colza, de lin ou de cameline, ou petits poissons (anchois, sardines, maquereaux). Une fois de plus, tout est une question de proportion !<br><br>De plus, favorisez les <a aria-label=\"fruits et l\u00e9gumes de saison (opens in a new tab)\" href=\"https:\/\/www.myzen.tv\/fr\/les-fruits-et-legumes-du-printemps\/\" target=\"_blank\" rel=\"noreferrer noopener\">fruits et l\u00e9gumes de saison<\/a> et en <strong>circuit court<\/strong>, afin de pr\u00e9server l\u2019<strong>environnement<\/strong> et donner un coup de pouce aux producteurs locaux.<\/p>\n\n\n\n<p>Comme diraient les anglais, \u201c<em>apple a day keeps the doctor away!<\/em>\u201d, comprenez, \u201c<em>Manger une pomme chaque jour vous d\u00e9pensera d\u2019aller chez le m\u00e9decin!<\/em>\u201d. <\/p>\n\n\n\n<p>Pour plus de conseils, rendez-vous sur notre <a href=\"https:\/\/watch.myzen.tv\/\" target=\"_blank\" rel=\"noreferrer noopener\">plateforme de streaming<\/a> !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est la grande question du moment ! Cela para\u00eet \u00eatre une chose impossible, et pourtant, il existe une multitude de petites choses simples et naturelles \u00e0 faire au quotidien pour renforcer votre syst\u00e8me immunitaire. MyZen TV vous explique tout. Manger une orange plut\u00f4t qu&rsquo;un jus Vous n\u2019imaginez pas tous les bienfaits que votre corps pourra [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1644415,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","filesize_raw":"","footnotes":""},"categories":[16,9],"tags":[109,110,111,164,193,113,108,195],"group":[],"support":[],"class_list":["post-1644413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-body-and-soul","tag-bienfaits-du-sommeil","tag-fruits","tag-legumes","tag-nature","tag-naturopathie","tag-saison","tag-sommeil","tag-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5 Astuces Pour Booster Son Syst\u00e8me Immunitaire - MyZen TV<\/title>\n<meta name=\"description\" content=\"MyZen TV vous donnes divers astuces pour booster votre syst\u00e8me immunitaire pendant l&#039;hiver et les p\u00e9riodes froides !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 Astuces Pour Booster Son Syst\u00e8me Immunitaire - MyZen TV\" \/>\n<meta property=\"og:description\" content=\"MyZen TV vous donnes divers astuces pour booster votre syst\u00e8me immunitaire pendant l&#039;hiver et les p\u00e9riodes froides !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/\" \/>\n<meta property=\"og:site_name\" content=\"MyZen TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myzen.tv.fr\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-26T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-22T15:34:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/national-cancer-institute-P6ID8cthfVA-unsplash-scaled-e1676989160938.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1081\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coline Lehembre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coline Lehembre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 Astuces Pour Booster Son Syst\u00e8me Immunitaire - MyZen TV","description":"MyZen TV vous donnes divers astuces pour booster votre syst\u00e8me immunitaire pendant l'hiver et les p\u00e9riodes froides !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/","og_locale":"fr_FR","og_type":"article","og_title":"5 Astuces Pour Booster Son Syst\u00e8me Immunitaire - MyZen TV","og_description":"MyZen TV vous donnes divers astuces pour booster votre syst\u00e8me immunitaire pendant l'hiver et les p\u00e9riodes froides !","og_url":"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/","og_site_name":"MyZen TV","article_publisher":"https:\/\/www.facebook.com\/myzen.tv.fr\/","article_published_time":"2023-02-26T06:00:00+00:00","article_modified_time":"2023-02-22T15:34:06+00:00","og_image":[{"width":1920,"height":1081,"url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/national-cancer-institute-P6ID8cthfVA-unsplash-scaled-e1676989160938.jpg","type":"image\/jpeg"}],"author":"Coline Lehembre","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Coline Lehembre","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/#article","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/"},"author":{"name":"Coline Lehembre","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/person\/7dd971c60a51df9ea643a930bef7d416"},"headline":"5 astuces pour booster son syst\u00e8me immunitaire naturellement","datePublished":"2023-02-26T06:00:00+00:00","dateModified":"2023-02-22T15:34:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/"},"wordCount":630,"publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/national-cancer-institute-P6ID8cthfVA-unsplash-scaled-e1676989160938.jpg","keywords":["bienfaits du sommeil","fruits","l\u00e9gumes","nature","naturopathie","saison","sommeil","sport"],"articleSection":["A la une","Body &amp; soul"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/","url":"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/","name":"5 Astuces Pour Booster Son Syst\u00e8me Immunitaire - MyZen TV","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/#primaryimage"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/national-cancer-institute-P6ID8cthfVA-unsplash-scaled-e1676989160938.jpg","datePublished":"2023-02-26T06:00:00+00:00","dateModified":"2023-02-22T15:34:06+00:00","description":"MyZen TV vous donnes divers astuces pour booster votre syst\u00e8me immunitaire pendant l'hiver et les p\u00e9riodes froides !","breadcrumb":{"@id":"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/#primaryimage","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/national-cancer-institute-P6ID8cthfVA-unsplash-scaled-e1676989160938.jpg","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/04\/national-cancer-institute-P6ID8cthfVA-unsplash-scaled-e1676989160938.jpg","width":1920,"height":1081},{"@type":"BreadcrumbList","@id":"https:\/\/www.myzen.tv\/fr\/5-astuces-pour-booster-son-systeme-immunitaire-naturellement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.myzen.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"5 astuces pour booster son syst\u00e8me immunitaire naturellement"}]},{"@type":"WebSite","@id":"https:\/\/www.myzen.tv\/fr\/#website","url":"https:\/\/www.myzen.tv\/fr\/","name":"MyZen TV","description":"Your lifestyle and well-being channel","publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myzen.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.myzen.tv\/fr\/#organization","name":"MyZen TV","url":"https:\/\/www.myzen.tv\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","width":512,"height":512,"caption":"MyZen TV"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myzen.tv.fr\/","https:\/\/www.instagram.com\/myzentv\/"]},{"@type":"Person","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/person\/7dd971c60a51df9ea643a930bef7d416","name":"Coline Lehembre","url":"https:\/\/www.myzen.tv\/fr\/author\/lehembre\/"}]}},"_links":{"self":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1644413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/comments?post=1644413"}],"version-history":[{"count":7,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1644413\/revisions"}],"predecessor-version":[{"id":1697181,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1644413\/revisions\/1697181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media\/1644415"}],"wp:attachment":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media?parent=1644413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/categories?post=1644413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/tags?post=1644413"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/group?post=1644413"},{"taxonomy":"support","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/support?post=1644413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}