{"id":1676965,"date":"2021-10-25T05:00:00","date_gmt":"2021-10-25T05:00:00","guid":{"rendered":"https:\/\/www.myzen.tv\/?p=1676965"},"modified":"2021-10-22T12:57:05","modified_gmt":"2021-10-22T12:57:05","slug":"6-aliments-bons-pour-la-sante","status":"publish","type":"post","link":"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/","title":{"rendered":"6 aliments bons pour la sant\u00e9"},"content":{"rendered":"\n<p><strong>MyZen TV <\/strong>vous propose de d\u00e9couvrir 6 aliments qui sont bons pour votre sant\u00e9. De quoi remplir votre frigo et vos placards !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1) <strong>Les l\u00e9gumes orang\u00e9s<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/melanie-hughes-JOqIPIjmUyQ-unsplash-1-1024x683.jpg\" alt=\"\" class=\"wp-image-1676993\" srcset=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/melanie-hughes-JOqIPIjmUyQ-unsplash-1-1024x683.jpg 1024w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/melanie-hughes-JOqIPIjmUyQ-unsplash-1-300x200.jpg 300w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/melanie-hughes-JOqIPIjmUyQ-unsplash-1-768x512.jpg 768w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/melanie-hughes-JOqIPIjmUyQ-unsplash-1-1536x1024.jpg 1536w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/melanie-hughes-JOqIPIjmUyQ-unsplash-1-2048x1365.jpg 2048w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/melanie-hughes-JOqIPIjmUyQ-unsplash-1-285x190.jpg 285w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/melanie-hughes-JOqIPIjmUyQ-unsplash-1-210x140.jpg 210w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/melanie-hughes-JOqIPIjmUyQ-unsplash-1-533x355.jpg 533w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Excellents pour le <strong>syst\u00e8me immunitaire<\/strong>, les <strong>articulations<\/strong> et la <strong>digestion<\/strong>, ces aliments sont \u00e0 consommer sans mod\u00e9ration.<\/p>\n\n\n\n<p>Une recette que vous devez absolument tester&nbsp;: Pur\u00e9e de courge butternut au curry, pour changer de la traditionnelle pur\u00e9e de pommes de terre. Un vrai d\u00e9lice&nbsp;!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2) <strong>Les \u00e9pinards<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"685\" src=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/chiara-conti-4TY1uOJ5LG4-unsplash-1024x685.jpg\" alt=\"\" class=\"wp-image-1676975\" srcset=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/chiara-conti-4TY1uOJ5LG4-unsplash-1024x685.jpg 1024w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/chiara-conti-4TY1uOJ5LG4-unsplash-300x201.jpg 300w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/chiara-conti-4TY1uOJ5LG4-unsplash-768x514.jpg 768w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/chiara-conti-4TY1uOJ5LG4-unsplash-1536x1028.jpg 1536w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/chiara-conti-4TY1uOJ5LG4-unsplash-2048x1371.jpg 2048w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/chiara-conti-4TY1uOJ5LG4-unsplash-284x190.jpg 284w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/chiara-conti-4TY1uOJ5LG4-unsplash-209x140.jpg 209w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/chiara-conti-4TY1uOJ5LG4-unsplash-530x355.jpg 530w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Remplis de <strong>vitamine K<\/strong>, <strong>d\u2019antioxydants<\/strong> et de <strong>fer<\/strong>, les \u00e9pinards ajoutent de la saveur et des nutriments dans n\u2019importe quelle recette&nbsp;! Ils lutteraient \u00e9galement contre l\u2019acn\u00e9, les rides et minimiseraient les risques de maladies cardiaques gr\u00e2ce au <strong>potassium<\/strong>, <strong>magn\u00e9sium<\/strong> et <strong>folate<\/strong> qu\u2019ils contiennent.<\/p>\n\n\n\n<p>Une recette que vous devez absolument tester&nbsp;: le toast aux \u00e9pinards et \u0153ufs poch\u00e9s, pour un petit d\u00e9jeuner original et complet&nbsp;!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3) <strong>Les l\u00e9gumineuses<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/andrey-bond-iSAt1qAFt7Q-unsplash-1024x684.jpg\" alt=\"\" class=\"wp-image-1676977\" srcset=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/andrey-bond-iSAt1qAFt7Q-unsplash-1024x684.jpg 1024w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/andrey-bond-iSAt1qAFt7Q-unsplash-300x200.jpg 300w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/andrey-bond-iSAt1qAFt7Q-unsplash-768x513.jpg 768w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/andrey-bond-iSAt1qAFt7Q-unsplash-1536x1025.jpg 1536w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/andrey-bond-iSAt1qAFt7Q-unsplash-2048x1367.jpg 2048w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/andrey-bond-iSAt1qAFt7Q-unsplash-285x190.jpg 285w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/andrey-bond-iSAt1qAFt7Q-unsplash-210x140.jpg 210w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/andrey-bond-iSAt1qAFt7Q-unsplash-532x355.jpg 532w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Les <strong>l\u00e9gumineuses<\/strong> favorisent la bonne digestion, sont riches en <strong>prot\u00e9ines<\/strong>, en <strong>fibres<\/strong>, en <strong>magn\u00e9sium<\/strong> et en <strong>antioxydants<\/strong>. De plus, elles diminuent le cholest\u00e9rol et nourrissent le syst\u00e8me nerveux.<\/p>\n\n\n\n<p>Une recette que vous devez absolument tester&nbsp;: le Dahl de lentilles coco, un repas sain r\u00e9unissant de nombreuses saveurs venues d\u2019Inde&nbsp;!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4) <strong>L\u2019avocat<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/louis-hansel-XGNPO89fqV0-unsplash-1024x683.jpg\" alt=\"\" class=\"wp-image-1676981\" srcset=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/louis-hansel-XGNPO89fqV0-unsplash-1024x683.jpg 1024w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/louis-hansel-XGNPO89fqV0-unsplash-300x200.jpg 300w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/louis-hansel-XGNPO89fqV0-unsplash-768x512.jpg 768w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/louis-hansel-XGNPO89fqV0-unsplash-1536x1024.jpg 1536w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/louis-hansel-XGNPO89fqV0-unsplash-2048x1365.jpg 2048w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/louis-hansel-XGNPO89fqV0-unsplash-285x190.jpg 285w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/louis-hansel-XGNPO89fqV0-unsplash-210x140.jpg 210w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/louis-hansel-XGNPO89fqV0-unsplash-533x355.jpg 533w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>L\u2019avocat est une valeur s\u00fbre : il contient de nombreux<strong> antioxydants<\/strong> et poss\u00e8de une substance permettant de r\u00e9duire l\u2019absorption de mauvais cholest\u00e9rol dans les aliments.<\/p>\n\n\n\n<p>Une recette que vous devez absolument tester&nbsp;: la salade aux crevettes, pamplemousse et avocat, une recette pleine de fra\u00eecheur, haute en couleur et en saveur&nbsp;!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5) <strong>Les agrumes<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"685\" src=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/ben-ashby-TAqEFzBEKbY-unsplash-1024x685.jpg\" alt=\"\" class=\"wp-image-1676983\" srcset=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/ben-ashby-TAqEFzBEKbY-unsplash-1024x685.jpg 1024w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/ben-ashby-TAqEFzBEKbY-unsplash-300x201.jpg 300w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/ben-ashby-TAqEFzBEKbY-unsplash-768x514.jpg 768w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/ben-ashby-TAqEFzBEKbY-unsplash-1536x1028.jpg 1536w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/ben-ashby-TAqEFzBEKbY-unsplash-2048x1371.jpg 2048w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/ben-ashby-TAqEFzBEKbY-unsplash-284x190.jpg 284w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/ben-ashby-TAqEFzBEKbY-unsplash-209x140.jpg 209w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/ben-ashby-TAqEFzBEKbY-unsplash-530x355.jpg 530w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Saviez-vous que les agrumes \u00e9taient excellents pour la <strong>digestion<\/strong> et la <strong>pression sanguine<\/strong>&nbsp;? En plus de ces superpouvoirs, les agrumes servent \u00e0 combattre le rhume tout en renfor\u00e7ant le <strong>syst\u00e8me immunitaire<\/strong>. De quoi vous motiver \u00e0 en manger plus souvent&nbsp;!<\/p>\n\n\n\n<p>Une recette que vous devez absolument tester&nbsp;: le smoothie banane-agrumes, une boisson remplie de vitamines et d\u2019\u00e9nergie&nbsp;!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">6) <strong>Le chocolat noir<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"612\" src=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/charisse-kenion-tWe8ib-cnXY-unsplash-1024x612.jpg\" alt=\"\" class=\"wp-image-1676979\" srcset=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/charisse-kenion-tWe8ib-cnXY-unsplash-1024x612.jpg 1024w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/charisse-kenion-tWe8ib-cnXY-unsplash-300x179.jpg 300w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/charisse-kenion-tWe8ib-cnXY-unsplash-768x459.jpg 768w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/charisse-kenion-tWe8ib-cnXY-unsplash-1536x917.jpg 1536w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/charisse-kenion-tWe8ib-cnXY-unsplash-2048x1223.jpg 2048w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/charisse-kenion-tWe8ib-cnXY-unsplash-318x190.jpg 318w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/charisse-kenion-tWe8ib-cnXY-unsplash-235x140.jpg 235w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/charisse-kenion-tWe8ib-cnXY-unsplash-540x322.jpg 540w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u00c7a vous redonne le sourire n\u2019est-ce pas&nbsp;? Riche en <strong>flavono\u00efdes<\/strong>, le chocolat noir permet de lutter contre l\u2019apparition de nombreux probl\u00e8mes cardiaques. 45 grammes de chocolat noir par jour peuvent permettre de r\u00e9duire de 10% les risques de subir une crise cardiaque.<\/p>\n\n\n\n<p>Une recette que vous devez absolument tester&nbsp;: le smoothie bowl chocolat noir, banane, noisettes et noix de coco, un petit encas facile \u00e0 faire, sain et gourmand.<\/p>\n\n\n\n<p>Voil\u00e0 6 aliments qui vous feront garder la forme m\u00eame en plein hiver.<\/p>\n\n\n\n<p>Pour plus de conseils pour \u00eatre en forme tout l\u2019hiver, rendez-vous sur l\u2019article \u201c<a href=\"https:\/\/www.myzen.tv\/fr\/5-cures-pour-ne-pas-tomber-malade-cet-hiver\/\">5 cures pour ne pas tomber malade cet hiver<\/a>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MyZen TV vous propose de d\u00e9couvrir 6 aliments qui sont bons pour votre sant\u00e9. De quoi remplir votre frigo et vos placards ! 1) Les l\u00e9gumes orang\u00e9s Excellents pour le syst\u00e8me immunitaire, les articulations et la digestion, ces aliments sont \u00e0 consommer sans mod\u00e9ration. Une recette que vous devez absolument tester&nbsp;: Pur\u00e9e de courge butternut [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1676969,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"episode_type":"audio","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","filesize_raw":"","footnotes":""},"categories":[50],"tags":[736,746,203],"group":[],"support":[],"class_list":["post-1676965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bien-etre-au-quotidien","tag-bonne-alimentation","tag-manger-sain-et-equilibre","tag-nutrition"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>6 aliments bons pour la sant\u00e9 - MyZen TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6 aliments bons pour la sant\u00e9 - MyZen TV\" \/>\n<meta property=\"og:description\" content=\"MyZen TV vous propose de d\u00e9couvrir 6 aliments qui sont bons pour votre sant\u00e9. De quoi remplir votre frigo et vos placards ! 1) Les l\u00e9gumes orang\u00e9s Excellents pour le syst\u00e8me immunitaire, les articulations et la digestion, ces aliments sont \u00e0 consommer sans mod\u00e9ration. Une recette que vous devez absolument tester&nbsp;: Pur\u00e9e de courge butternut [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/\" \/>\n<meta property=\"og:site_name\" content=\"MyZen TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myzen.tv.fr\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-25T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-22T12:57:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/nathan-dumlao-k3DmHnnAH3M-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1708\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valentine Legrand\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valentine Legrand\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6 aliments bons pour la sant\u00e9 - MyZen TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/","og_locale":"fr_FR","og_type":"article","og_title":"6 aliments bons pour la sant\u00e9 - MyZen TV","og_description":"MyZen TV vous propose de d\u00e9couvrir 6 aliments qui sont bons pour votre sant\u00e9. De quoi remplir votre frigo et vos placards ! 1) Les l\u00e9gumes orang\u00e9s Excellents pour le syst\u00e8me immunitaire, les articulations et la digestion, ces aliments sont \u00e0 consommer sans mod\u00e9ration. Une recette que vous devez absolument tester&nbsp;: Pur\u00e9e de courge butternut [&hellip;]","og_url":"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/","og_site_name":"MyZen TV","article_publisher":"https:\/\/www.facebook.com\/myzen.tv.fr\/","article_published_time":"2021-10-25T05:00:00+00:00","article_modified_time":"2021-10-22T12:57:05+00:00","og_image":[{"width":1708,"height":2560,"url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/nathan-dumlao-k3DmHnnAH3M-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Valentine Legrand","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Valentine Legrand","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/#article","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/"},"author":{"name":"Valentine Legrand","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/person\/ba8976f459aa0de0a454fa1d61201da2"},"headline":"6 aliments bons pour la sant\u00e9","datePublished":"2021-10-25T05:00:00+00:00","dateModified":"2021-10-22T12:57:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/"},"wordCount":455,"publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/nathan-dumlao-k3DmHnnAH3M-unsplash-scaled.jpg","keywords":["bonne alimentation","manger sain et \u00e9quilibr\u00e9","nutrition"],"articleSection":["Bien-\u00eatre au quotidien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/","url":"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/","name":"6 aliments bons pour la sant\u00e9 - MyZen TV","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/#primaryimage"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/nathan-dumlao-k3DmHnnAH3M-unsplash-scaled.jpg","datePublished":"2021-10-25T05:00:00+00:00","dateModified":"2021-10-22T12:57:05+00:00","breadcrumb":{"@id":"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/#primaryimage","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/nathan-dumlao-k3DmHnnAH3M-unsplash-scaled.jpg","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/10\/nathan-dumlao-k3DmHnnAH3M-unsplash-scaled.jpg","width":1708,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.myzen.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"6 aliments bons pour la sant\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.myzen.tv\/fr\/#website","url":"https:\/\/www.myzen.tv\/fr\/","name":"MyZen TV","description":"Your lifestyle and well-being channel","publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myzen.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.myzen.tv\/fr\/#organization","name":"MyZen TV","url":"https:\/\/www.myzen.tv\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","width":512,"height":512,"caption":"MyZen TV"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myzen.tv.fr\/","https:\/\/www.instagram.com\/myzentv\/"]},{"@type":"Person","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/person\/ba8976f459aa0de0a454fa1d61201da2","name":"Valentine Legrand","url":"https:\/\/www.myzen.tv\/fr\/author\/legrand\/"}]}},"_links":{"self":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1676965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/comments?post=1676965"}],"version-history":[{"count":5,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1676965\/revisions"}],"predecessor-version":[{"id":1676996,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1676965\/revisions\/1676996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media\/1676969"}],"wp:attachment":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media?parent=1676965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/categories?post=1676965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/tags?post=1676965"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/group?post=1676965"},{"taxonomy":"support","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/support?post=1676965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}