{"id":1687935,"date":"2022-07-30T06:00:00","date_gmt":"2022-07-30T06:00:00","guid":{"rendered":"https:\/\/www.myzen.tv\/?p=1687935"},"modified":"2023-02-01T13:42:08","modified_gmt":"2023-02-01T13:42:08","slug":"recette-smoothie-au-chocolat-et-aux-noix","status":"publish","type":"post","link":"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/","title":{"rendered":"Smoothie au chocolat et aux noix"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Ingr\u00e9dients : <\/h2>\n\n\n\n<ul class=\"liste-recette wp-block-list\"><li>120ml de lait<\/li><li>Un demi avocat<\/li><li>Une demi <a href=\"https:\/\/www.myzen.tv\/fr\/6-aliments-bons-pour-la-sante\/\">banane<\/a><\/li><li>1 abricot<\/li><li>2 cuill\u00e8res \u00e0 soupe de cacao en poudre<\/li><li>1 cuill\u00e8re \u00e0 soupe de miel<\/li><li>15gr de noix<\/li><li>Des gla\u00e7ons<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Recette : <\/h2>\n\n\n\n<ul class=\"tache-recette wp-block-list\"><li>\u00c9plucher et d\u00e9couper tous les fruits en morceaux.<\/li><li>R\u00e9duire en petits morceaux les noix<\/li><li>Dans un mixeur, mettre les fruits, les noix, le lait, le cacao et le miel. <\/li><li>Rajouter les gla\u00e7ons. <\/li><li>Mixer le tout.<\/li><li>D\u00e9gustez de pr\u00e9f\u00e9rence tr\u00e8s frais. <\/li><\/ul>\n\n\n\n<p>Retrouvez la recette en vid\u00e9o sur notre <a href=\"https:\/\/watch.myzen.tv\/content\/smoothie-mania-smoothie-au-chocolat-et-aux-noix\">plateforme de streaming MyZen TV<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingr\u00e9dients : 120ml de lait Un demi avocat Une demi banane 1 abricot 2 cuill\u00e8res \u00e0 soupe de cacao en poudre 1 cuill\u00e8re \u00e0 soupe de miel 15gr de noix Des gla\u00e7ons Recette : \u00c9plucher et d\u00e9couper tous les fruits en morceaux. R\u00e9duire en petits morceaux les noix Dans un mixeur, mettre les fruits, les [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":1687936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","filesize_raw":"","footnotes":""},"categories":[29,1269],"tags":[187,110,229,228],"group":[314],"support":[1270],"class_list":["post-1687935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-ne-pas-rater","category-recettes","tag-cuisine","tag-fruits","tag-recette","tag-smoothie","group-cuisine","support-recette"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Smoothie au chocolat et aux noix - MyZen TV<\/title>\n<meta name=\"description\" content=\"Pour cette recette il vous faudra du lait, de l\u2019avocat, de la banane, de la poudre de cacao, du miel, des noix et de l\u2019abricot.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Smoothie au chocolat et aux noix - MyZen TV\" \/>\n<meta property=\"og:description\" content=\"Pour cette recette il vous faudra du lait, de l\u2019avocat, de la banane, de la poudre de cacao, du miel, des noix et de l\u2019abricot.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/\" \/>\n<meta property=\"og:site_name\" content=\"MyZen TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myzen.tv.fr\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-30T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-01T13:42:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/07\/Capture-de\u0301cran-2022-07-25-a\u0300-16.07.00.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1343\" \/>\n\t<meta property=\"og:image:height\" content=\"967\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gabrielle Cattier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabrielle Cattier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Smoothie au chocolat et aux noix - MyZen TV","description":"Pour cette recette il vous faudra du lait, de l\u2019avocat, de la banane, de la poudre de cacao, du miel, des noix et de l\u2019abricot.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/","og_locale":"fr_FR","og_type":"article","og_title":"Smoothie au chocolat et aux noix - MyZen TV","og_description":"Pour cette recette il vous faudra du lait, de l\u2019avocat, de la banane, de la poudre de cacao, du miel, des noix et de l\u2019abricot.","og_url":"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/","og_site_name":"MyZen TV","article_publisher":"https:\/\/www.facebook.com\/myzen.tv.fr\/","article_published_time":"2022-07-30T06:00:00+00:00","article_modified_time":"2023-02-01T13:42:08+00:00","og_image":[{"width":1343,"height":967,"url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/07\/Capture-de\u0301cran-2022-07-25-a\u0300-16.07.00.png","type":"image\/png"}],"author":"Gabrielle Cattier","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gabrielle Cattier","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/#article","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/"},"author":{"name":"Gabrielle Cattier","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/person\/60c38aefd5fdad55ca411a73751f70bb"},"headline":"Smoothie au chocolat et aux noix","datePublished":"2022-07-30T06:00:00+00:00","dateModified":"2023-02-01T13:42:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/"},"wordCount":97,"publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/07\/Capture-de\u0301cran-2022-07-25-a\u0300-16.07.00.png","keywords":["cuisine","fruits","recette","smoothie"],"articleSection":["\u00c0 ne pas rater","Recettes"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/","url":"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/","name":"Smoothie au chocolat et aux noix - MyZen TV","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/#primaryimage"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/07\/Capture-de\u0301cran-2022-07-25-a\u0300-16.07.00.png","datePublished":"2022-07-30T06:00:00+00:00","dateModified":"2023-02-01T13:42:08+00:00","description":"Pour cette recette il vous faudra du lait, de l\u2019avocat, de la banane, de la poudre de cacao, du miel, des noix et de l\u2019abricot.","breadcrumb":{"@id":"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/#primaryimage","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/07\/Capture-de\u0301cran-2022-07-25-a\u0300-16.07.00.png","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/07\/Capture-de\u0301cran-2022-07-25-a\u0300-16.07.00.png","width":1343,"height":967},{"@type":"BreadcrumbList","@id":"https:\/\/www.myzen.tv\/fr\/recette-smoothie-au-chocolat-et-aux-noix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.myzen.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"Cuisine","item":"https:\/\/www.myzen.tv\/fr\/theme\/cuisine\/"},{"@type":"ListItem","position":3,"name":"Smoothie au chocolat et aux noix"}]},{"@type":"WebSite","@id":"https:\/\/www.myzen.tv\/fr\/#website","url":"https:\/\/www.myzen.tv\/fr\/","name":"MyZen TV","description":"Your lifestyle and well-being channel","publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myzen.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.myzen.tv\/fr\/#organization","name":"MyZen TV","url":"https:\/\/www.myzen.tv\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","width":512,"height":512,"caption":"MyZen TV"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myzen.tv.fr\/","https:\/\/www.instagram.com\/myzentv\/"]},{"@type":"Person","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/person\/60c38aefd5fdad55ca411a73751f70bb","name":"Gabrielle Cattier","url":"https:\/\/www.myzen.tv\/fr\/author\/gabrielle-cattier\/"}]}},"_links":{"self":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1687935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/comments?post=1687935"}],"version-history":[{"count":4,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1687935\/revisions"}],"predecessor-version":[{"id":1696872,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1687935\/revisions\/1696872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media\/1687936"}],"wp:attachment":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media?parent=1687935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/categories?post=1687935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/tags?post=1687935"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/group?post=1687935"},{"taxonomy":"support","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/support?post=1687935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}