{"id":1693000,"date":"2022-11-19T05:00:00","date_gmt":"2022-11-19T05:00:00","guid":{"rendered":"https:\/\/www.myzen.tv\/?p=1693000"},"modified":"2022-11-25T13:57:19","modified_gmt":"2022-11-25T13:57:19","slug":"3-aliments-pour-lutter-contre-les-virus","status":"publish","type":"post","link":"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/","title":{"rendered":"3 aliments pour lutter contre les virus"},"content":{"rendered":"\n<p>Avec le froid qui arrive, notre syst\u00e8me immunitaire est mis \u00e0 rude \u00e9preuve. Les virus nous attaquent plus facilement. Pour rester en pleine forme, MyZen TV vous propose de d\u00e9couvrir<strong> trois aliments qui vous permettent de booster votre syst\u00e8me immunitaire<\/strong> !  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L&rsquo;ail<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/09\/pexels-karolina-grabowska-4022126-1024x683.jpg\" alt=\"\" class=\"wp-image-1690887\" srcset=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/09\/pexels-karolina-grabowska-4022126-1024x683.jpg 1024w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/09\/pexels-karolina-grabowska-4022126-300x200.jpg 300w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/09\/pexels-karolina-grabowska-4022126-768x512.jpg 768w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/09\/pexels-karolina-grabowska-4022126-1536x1024.jpg 1536w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/09\/pexels-karolina-grabowska-4022126-2048x1365.jpg 2048w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/09\/pexels-karolina-grabowska-4022126-285x190.jpg 285w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/09\/pexels-karolina-grabowska-4022126-210x140.jpg 210w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/09\/pexels-karolina-grabowska-4022126-533x355.jpg 533w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Sans surprise, l&rsquo;ail est, depuis l&rsquo;antiquit\u00e9, l&rsquo;un des plus fid\u00e8les alli\u00e9s du syst\u00e8me immunitaire. Ses&nbsp;<strong>propri\u00e9t\u00e9s antibact\u00e9riennes et anti-inflammatoires<\/strong> sont bien connues. De plus, sa haute teneur en&nbsp;<strong>soufre<\/strong>&nbsp;inhibe la croissance bact\u00e9rienne. <\/p>\n\n\n\n<p>Ainsi, l&rsquo;ail est tr\u00e8s efficace pour lutter contre les petites maladies infectieuses de l&rsquo;hiver telles que le<strong> rhume<\/strong>, <strong>l&rsquo;angine<\/strong> ou encore<strong> le mal de gorge<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le chou fris\u00e9&nbsp;<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-pixabay-51372-1024x683.jpg\" alt=\"\" class=\"wp-image-1693001\" srcset=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-pixabay-51372-1024x683.jpg 1024w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-pixabay-51372-300x200.jpg 300w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-pixabay-51372-768x512.jpg 768w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-pixabay-51372-1536x1024.jpg 1536w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-pixabay-51372-2048x1365.jpg 2048w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-pixabay-51372-285x190.jpg 285w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-pixabay-51372-210x140.jpg 210w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-pixabay-51372-533x355.jpg 533w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Aliment inattendu pour notre sant\u00e9 ! Le choux fris\u00e9 est gorg\u00e9 de <strong>vitamine C<\/strong>, un puissant alli\u00e9 pour lutter contre les virus. En effet, elle&nbsp;<strong>stimule les r\u00e9actions immunitaires<\/strong>, augmente la&nbsp;<strong>fabrication des anticorps, prot\u00e8ge la paroi des vaisseaux sanguins, aide \u00e0 assimiler le fer et \u00e0 cicatriser<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Par son absorption r\u00e9guli\u00e8re elle pr\u00e9vient des premiers sympt\u00f4mes et peut freiner l&rsquo;infection.<\/p>\n\n\n\n<p>Il est conseill\u00e9 d&rsquo;absorber environ&nbsp;<strong>110 mg par jour<\/strong> de Vitamine C. Et bonne nouvelle, le chou fris\u00e9 en comporte 145mg pour 100g ! <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le miel <\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-roman-odintsov-6422025-1024x683.jpg\" alt=\"\" class=\"wp-image-1693003\" srcset=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-roman-odintsov-6422025-1024x683.jpg 1024w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-roman-odintsov-6422025-300x200.jpg 300w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-roman-odintsov-6422025-768x512.jpg 768w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-roman-odintsov-6422025-1536x1024.jpg 1536w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-roman-odintsov-6422025-2048x1365.jpg 2048w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-roman-odintsov-6422025-285x190.jpg 285w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-roman-odintsov-6422025-210x140.jpg 210w, https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-roman-odintsov-6422025-533x355.jpg 533w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Le miel contient de la propolis qui est un excellent atout pour <strong>booster son syst\u00e8me immunitaire<\/strong>. Antiviral, anti-inflammatoire, il facilite la formation d\u2019anticorps.<\/p>\n\n\n\n<p>\u00c0 tr\u00e8s vite sur <a href=\"https:\/\/www.myzen.tv\/fr\/\">MyZen Tv<\/a> ! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec le froid qui arrive, notre syst\u00e8me immunitaire est mis \u00e0 rude \u00e9preuve. Les virus nous attaquent plus facilement. Pour rester en pleine forme, MyZen TV vous propose de d\u00e9couvrir trois aliments qui vous permettent de booster votre syst\u00e8me immunitaire ! L&rsquo;ail Sans surprise, l&rsquo;ail est, depuis l&rsquo;antiquit\u00e9, l&rsquo;un des plus fid\u00e8les alli\u00e9s du syst\u00e8me [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":1693005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","filesize_raw":"","footnotes":""},"categories":[16],"tags":[],"group":[],"support":[],"class_list":["post-1693000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>3 aliments pour lutter contre les virus - MyZen TV<\/title>\n<meta name=\"description\" content=\"My Zen TV vous propose de d\u00e9couvrir trois aliments qui vous permettent de booster votre syst\u00e8me immunitaire !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 aliments pour lutter contre les virus - MyZen TV\" \/>\n<meta property=\"og:description\" content=\"My Zen TV vous propose de d\u00e9couvrir trois aliments qui vous permettent de booster votre syst\u00e8me immunitaire !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/\" \/>\n<meta property=\"og:site_name\" content=\"MyZen TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myzen.tv.fr\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-19T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-25T13:57:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-anna-shvets-3962294-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gilles Farina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilles Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 aliments pour lutter contre les virus - MyZen TV","description":"My Zen TV vous propose de d\u00e9couvrir trois aliments qui vous permettent de booster votre syst\u00e8me immunitaire !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/","og_locale":"fr_FR","og_type":"article","og_title":"3 aliments pour lutter contre les virus - MyZen TV","og_description":"My Zen TV vous propose de d\u00e9couvrir trois aliments qui vous permettent de booster votre syst\u00e8me immunitaire !","og_url":"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/","og_site_name":"MyZen TV","article_publisher":"https:\/\/www.facebook.com\/myzen.tv.fr\/","article_published_time":"2022-11-19T05:00:00+00:00","article_modified_time":"2022-11-25T13:57:19+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-anna-shvets-3962294-scaled.jpg","type":"image\/jpeg"}],"author":"Gilles Farina","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilles Farina","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/#article","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/"},"author":{"name":"Gilles Farina","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/person\/978a9e7addfdccd3326847815bc2aca6"},"headline":"3 aliments pour lutter contre les virus","datePublished":"2022-11-19T05:00:00+00:00","dateModified":"2022-11-25T13:57:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/"},"wordCount":245,"publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-anna-shvets-3962294-scaled.jpg","articleSection":["A la une"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/","url":"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/","name":"3 aliments pour lutter contre les virus - MyZen TV","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/#primaryimage"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-anna-shvets-3962294-scaled.jpg","datePublished":"2022-11-19T05:00:00+00:00","dateModified":"2022-11-25T13:57:19+00:00","description":"My Zen TV vous propose de d\u00e9couvrir trois aliments qui vous permettent de booster votre syst\u00e8me immunitaire !","breadcrumb":{"@id":"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/#primaryimage","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-anna-shvets-3962294-scaled.jpg","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/10\/pexels-anna-shvets-3962294-scaled.jpg","width":2560,"height":1707,"caption":"3 foods to boost your immune system"},{"@type":"BreadcrumbList","@id":"https:\/\/www.myzen.tv\/fr\/3-aliments-pour-lutter-contre-les-virus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.myzen.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"3 aliments pour lutter contre les virus"}]},{"@type":"WebSite","@id":"https:\/\/www.myzen.tv\/fr\/#website","url":"https:\/\/www.myzen.tv\/fr\/","name":"MyZen TV","description":"Your lifestyle and well-being channel","publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myzen.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.myzen.tv\/fr\/#organization","name":"MyZen TV","url":"https:\/\/www.myzen.tv\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","width":512,"height":512,"caption":"MyZen TV"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myzen.tv.fr\/","https:\/\/www.instagram.com\/myzentv\/"]},{"@type":"Person","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/person\/978a9e7addfdccd3326847815bc2aca6","name":"Gilles Farina","url":"https:\/\/www.myzen.tv\/fr\/author\/giles-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1693000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/comments?post=1693000"}],"version-history":[{"count":5,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1693000\/revisions"}],"predecessor-version":[{"id":1695321,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1693000\/revisions\/1695321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media\/1693005"}],"wp:attachment":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media?parent=1693000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/categories?post=1693000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/tags?post=1693000"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/group?post=1693000"},{"taxonomy":"support","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/support?post=1693000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}