{"id":1695459,"date":"2022-12-16T06:00:00","date_gmt":"2022-12-16T06:00:00","guid":{"rendered":"https:\/\/www.myzen.tv\/?p=1695459"},"modified":"2022-11-30T14:17:37","modified_gmt":"2022-11-30T14:17:37","slug":"decorations-de-noel-ecologiques-a-petit-prix","status":"publish","type":"post","link":"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/","title":{"rendered":"D\u00e9corations de No\u00ebl \u00e9cologiques \u00e0 petit prix !"},"content":{"rendered":"\n<p>C&rsquo;est une question que l&rsquo;on se pose de plus en plus au moment des f\u00eates. Comment passer un No\u00ebl plus responsable ? Bien \u00e9videment cela passe par les cadeaux, leurs <a href=\"https:\/\/www.myzen.tv\/fr\/?p=1695458\">emballages<\/a>, mais \u00e9galement par la d\u00e9coration. MyZen TV vous donne deux conseils pour avoir des <strong>d\u00e9corations de No\u00ebl plus \u00e9cologiques<\/strong>.<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Un conseil banal mais redoutablement efficace<strong> <\/strong>: <strong>la seconde main <\/strong>! N&rsquo;h\u00e9sitez pas \u00e0 parcourir les vides greniers peu de temps avant les f\u00eates, ils sont remplis de bonnes affaires. Il fait trop froid pour sortir ? Pas de panique, rendez-vous sur les sites sp\u00e9cialis\u00e9s en seconde main. Vous trouverez votre bonheur, et vous ferez un geste pour la plan\u00e8te.<\/li><li>Faites participer vos enfants \u00e0 des <strong>activit\u00e9s de cr\u00e9ations \u00e9coresponsable<\/strong>. Concr\u00e8tement, r\u00e9utilisez de vieux objets dans la maison pour confectionner de merveilleuses d\u00e9corations de fin d&rsquo;ann\u00e9e. Vous souvenez-vous des couronnes de No\u00ebl que l&rsquo;on faisait \u00e0 l&rsquo;\u00e9cole ? C&rsquo;est un exemple mais il est \u00e0 compl\u00e9ter avec un peu d&rsquo;objets d&rsquo;occasion.   <\/li><\/ol>\n\n\n\n<p>Et vous, quelles sont vos astuces pour cr\u00e9er des d\u00e9corations de No\u00ebl \u00e9cologiques ? <\/p>\n\n\n\n<p>Rendez-vous sur <a href=\"https:\/\/watch.myzen.tv\/\">notre plateforme de streaming<\/a> pour retrouver nos programmes sur les f\u00eates de fin d&rsquo;ann\u00e9e !  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est une question que l&rsquo;on se pose de plus en plus au moment des f\u00eates. Comment passer un No\u00ebl plus responsable ? Bien \u00e9videment cela passe par les cadeaux, leurs emballages, mais \u00e9galement par la d\u00e9coration. MyZen TV vous donne deux conseils pour avoir des d\u00e9corations de No\u00ebl plus \u00e9cologiques. Un conseil banal mais redoutablement [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":1695465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","filesize_raw":"","footnotes":""},"categories":[16],"tags":[831],"group":[],"support":[],"class_list":["post-1695459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","tag-noel-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9corations de No\u00ebl \u00e9cologiques \u00e0 petit prix ! - MyZen TV<\/title>\n<meta name=\"description\" content=\"Comment passer des f\u00eates plus \u00e9cologique ? MyZen TV vous donne deux conseils pour des d\u00e9corations de No\u00ebl plus \u00e9cologiques !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9corations de No\u00ebl \u00e9cologiques \u00e0 petit prix ! - MyZen TV\" \/>\n<meta property=\"og:description\" content=\"Comment passer des f\u00eates plus \u00e9cologique ? MyZen TV vous donne deux conseils pour des d\u00e9corations de No\u00ebl plus \u00e9cologiques !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/\" \/>\n<meta property=\"og:site_name\" content=\"MyZen TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myzen.tv.fr\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-16T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-30T14:17:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/11\/pexels-vlada-karpovich-6119570-scaled-e1669718607539.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"1081\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gilles Farina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilles Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9corations de No\u00ebl \u00e9cologiques \u00e0 petit prix ! - MyZen TV","description":"Comment passer des f\u00eates plus \u00e9cologique ? MyZen TV vous donne deux conseils pour des d\u00e9corations de No\u00ebl plus \u00e9cologiques !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9corations de No\u00ebl \u00e9cologiques \u00e0 petit prix ! - MyZen TV","og_description":"Comment passer des f\u00eates plus \u00e9cologique ? MyZen TV vous donne deux conseils pour des d\u00e9corations de No\u00ebl plus \u00e9cologiques !","og_url":"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/","og_site_name":"MyZen TV","article_publisher":"https:\/\/www.facebook.com\/myzen.tv.fr\/","article_published_time":"2022-12-16T06:00:00+00:00","article_modified_time":"2022-11-30T14:17:37+00:00","og_image":[{"width":1707,"height":1081,"url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/11\/pexels-vlada-karpovich-6119570-scaled-e1669718607539.jpg","type":"image\/jpeg"}],"author":"Gilles Farina","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilles Farina","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/#article","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/"},"author":{"name":"Gilles Farina","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/person\/978a9e7addfdccd3326847815bc2aca6"},"headline":"D\u00e9corations de No\u00ebl \u00e9cologiques \u00e0 petit prix !","datePublished":"2022-12-16T06:00:00+00:00","dateModified":"2022-11-30T14:17:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/"},"wordCount":213,"publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/11\/pexels-vlada-karpovich-6119570-scaled-e1669718607539.jpg","keywords":["No\u00ebl"],"articleSection":["A la une"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/","url":"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/","name":"D\u00e9corations de No\u00ebl \u00e9cologiques \u00e0 petit prix ! - MyZen TV","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/#primaryimage"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/11\/pexels-vlada-karpovich-6119570-scaled-e1669718607539.jpg","datePublished":"2022-12-16T06:00:00+00:00","dateModified":"2022-11-30T14:17:37+00:00","description":"Comment passer des f\u00eates plus \u00e9cologique ? MyZen TV vous donne deux conseils pour des d\u00e9corations de No\u00ebl plus \u00e9cologiques !","breadcrumb":{"@id":"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/#primaryimage","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/11\/pexels-vlada-karpovich-6119570-scaled-e1669718607539.jpg","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2022\/11\/pexels-vlada-karpovich-6119570-scaled-e1669718607539.jpg","width":1707,"height":1081,"caption":"D\u00e9corations de No\u00ebl \u00e9cologiques"},{"@type":"BreadcrumbList","@id":"https:\/\/www.myzen.tv\/fr\/decorations-de-noel-ecologiques-a-petit-prix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.myzen.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9corations de No\u00ebl \u00e9cologiques \u00e0 petit prix !"}]},{"@type":"WebSite","@id":"https:\/\/www.myzen.tv\/fr\/#website","url":"https:\/\/www.myzen.tv\/fr\/","name":"MyZen TV","description":"Your lifestyle and well-being channel","publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myzen.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.myzen.tv\/fr\/#organization","name":"MyZen TV","url":"https:\/\/www.myzen.tv\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","width":512,"height":512,"caption":"MyZen TV"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myzen.tv.fr\/","https:\/\/www.instagram.com\/myzentv\/"]},{"@type":"Person","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/person\/978a9e7addfdccd3326847815bc2aca6","name":"Gilles Farina","url":"https:\/\/www.myzen.tv\/fr\/author\/giles-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1695459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/comments?post=1695459"}],"version-history":[{"count":2,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1695459\/revisions"}],"predecessor-version":[{"id":1695528,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/posts\/1695459\/revisions\/1695528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media\/1695465"}],"wp:attachment":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media?parent=1695459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/categories?post=1695459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/tags?post=1695459"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/group?post=1695459"},{"taxonomy":"support","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/support?post=1695459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}