{"id":1631168,"date":"2021-05-07T18:48:13","date_gmt":"2021-05-07T18:48:13","guid":{"rendered":"https:\/\/www.myzen.tv\/?post_type=programs&#038;p=1631168"},"modified":"2026-04-28T09:54:15","modified_gmt":"2026-04-28T09:54:15","slug":"11171-paddle-yoga-s00-e01","status":"publish","type":"program","link":"https:\/\/www.myzen.tv\/fr\/program\/episode\/11171-paddle-yoga-s00-e01","title":{"rendered":"Paddle Yoga"},"content":{"rendered":"<p>Val Kahl d\u00e9couvre, avec YOGAqua, les cours addictifs de yoga et zen sur un paddleboard, \u00e0 la plage de Marina Del Rey. Apr\u00e8s avoir appris \u00e0 faire des wraps d\u00e9licieux et sains dans le restaurant KYE&rsquo;S, elle fait un tour \u00e0 Malibu Wine Hikes &#8211; le jardin bio des vignes derri\u00e8re les c\u00e9l\u00e8bres plages de Malibu. Pendant cette d\u00e9couverte inoubliable, elle ne peut pas r\u00e9sister \u00e0 l&rsquo;envie de go\u00fbter une plante de moutarde, ou encore de nourrir et s&rsquo;amuser avec Stanley &#8211; la girafe star. Elle r\u00e9colte ensuite des l\u00e9gumes bios et frais au jardin de Saddle Rock!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans cet \u00e9pisode, Val Kahl va s\u2019essayer au yoga sur paddle, pr\u00e9parer des wraps au restaurant KYE\u2019S, faire un tour \u00e0 Malibu Wine Hikes, des vignes bios. Puis elle ira \u00e0 la rencontre d\u2019une girafe, avant de r\u00e9colter des l\u00e9gumes aux jardins Saddle Rock.<\/p>\n","protected":false},"featured_media":1565840,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"00:26:00","filesize":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","filesize_raw":""},"program_type":[32],"group":[319,272],"d_category":[1172],"genre":[1378],"class_list":["post-1631168","program","type-program","status-publish","format-standard","has-post-thumbnail","hentry","program_type-episode","group-bien-etre-sante","group-well-being-health","d_category-daily-wellbeing","genre-magazine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paddle Yoga - MyZen TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.myzen.tv\/fr\/program\/episode\/11171-paddle-yoga-s00-e01\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paddle Yoga - MyZen TV\" \/>\n<meta property=\"og:description\" content=\"Dans cet \u00e9pisode, Val Kahl va s\u2019essayer au yoga sur paddle, pr\u00e9parer des wraps au restaurant KYE\u2019S, faire un tour \u00e0 Malibu Wine Hikes, des vignes bios. Puis elle ira \u00e0 la rencontre d\u2019une girafe, avant de r\u00e9colter des l\u00e9gumes aux jardins Saddle Rock.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myzen.tv\/fr\/program\/episode\/11171-paddle-yoga-s00-e01\" \/>\n<meta property=\"og:site_name\" content=\"MyZen TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myzen.tv.fr\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T09:54:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/01\/my-zen-trendy-s-1-paddle-yoga.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paddle Yoga - MyZen TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.myzen.tv\/fr\/program\/episode\/11171-paddle-yoga-s00-e01\/","og_locale":"fr_FR","og_type":"article","og_title":"Paddle Yoga - MyZen TV","og_description":"Dans cet \u00e9pisode, Val Kahl va s\u2019essayer au yoga sur paddle, pr\u00e9parer des wraps au restaurant KYE\u2019S, faire un tour \u00e0 Malibu Wine Hikes, des vignes bios. Puis elle ira \u00e0 la rencontre d\u2019une girafe, avant de r\u00e9colter des l\u00e9gumes aux jardins Saddle Rock.","og_url":"https:\/\/www.myzen.tv\/fr\/program\/episode\/11171-paddle-yoga-s00-e01","og_site_name":"MyZen TV","article_publisher":"https:\/\/www.facebook.com\/myzen.tv.fr\/","article_modified_time":"2026-04-28T09:54:15+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/01\/my-zen-trendy-s-1-paddle-yoga.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/11171-paddle-yoga-s00-e01","url":"https:\/\/www.myzen.tv\/fr\/program\/episode\/11171-paddle-yoga-s00-e01","name":"Paddle Yoga - MyZen TV","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/11171-paddle-yoga-s00-e01#primaryimage"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/11171-paddle-yoga-s00-e01#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/01\/my-zen-trendy-s-1-paddle-yoga.jpg","datePublished":"2021-05-07T18:48:13+00:00","dateModified":"2026-04-28T09:54:15+00:00","breadcrumb":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/11171-paddle-yoga-s00-e01#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myzen.tv\/fr\/program\/episode\/11171-paddle-yoga-s00-e01"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/11171-paddle-yoga-s00-e01#primaryimage","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/01\/my-zen-trendy-s-1-paddle-yoga.jpg","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/01\/my-zen-trendy-s-1-paddle-yoga.jpg","width":1280,"height":720,"caption":"Join the trend-spotter, Val Kahl, to hunt some exquisite foods, current lifestyle and well-being locations in California and Paris."},{"@type":"BreadcrumbList","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/11171-paddle-yoga-s00-e01#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.myzen.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"Programs","item":"https:\/\/www.myzen.tv\/fr\/programs\/"},{"@type":"ListItem","position":3,"name":"Paddle Yoga"}]},{"@type":"WebSite","@id":"https:\/\/www.myzen.tv\/fr\/#website","url":"https:\/\/www.myzen.tv\/fr\/","name":"MyZen TV","description":"Your lifestyle and well-being channel","publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myzen.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.myzen.tv\/fr\/#organization","name":"MyZen TV","url":"https:\/\/www.myzen.tv\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","width":512,"height":512,"caption":"MyZen TV"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myzen.tv.fr\/","https:\/\/www.instagram.com\/myzentv\/"]}]}},"status_options":[{"label":"Inactive","value":"inactive"}],"_links":{"self":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/programs\/1631168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/programs"}],"about":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/types\/program"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media\/1565840"}],"wp:attachment":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media?parent=1631168"}],"wp:term":[{"taxonomy":"program_type","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/program_type?post=1631168"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/group?post=1631168"},{"taxonomy":"d_category","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/d_category?post=1631168"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/genre?post=1631168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}