{"id":1679101,"date":"2021-12-21T11:09:36","date_gmt":"2021-12-21T11:09:36","guid":{"rendered":"https:\/\/www.myzen.tv\/program\/\/12848-la-terre-vue-du-sport-s01-e14\/"},"modified":"2026-04-28T09:44:32","modified_gmt":"2026-04-28T09:44:32","slug":"12848-episode-14-s00-e14","status":"publish","type":"program","link":"https:\/\/www.myzen.tv\/fr\/program\/episode\/12848-episode-14-s00-e14","title":{"rendered":"\u00c9pisode 14"},"content":{"rendered":"<p>Dans cet \u00e9pisode, vous allez en prendre plein la vue en suivant des amateurs de sensations fortes en avion, en ULM ou encore en snowboard. Passez entre les rouleaux des vagues en surfant, et profitez d\u2019un coucher de soleil au bord de la plage. Ne manquez pas ces paysages \u00e0 couper le souffle ! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des paysages naturels m\u00e9lang\u00e9s \u00e0 des sports extr\u00eames captur\u00e9s avec des cam\u00e9ras embarqu\u00e9es pour d\u00e9couvrir les plus beaux paysages de la plan\u00e8te.<\/p>\n","protected":false},"featured_media":1679102,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"00:04:00","filesize":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","filesize_raw":""},"program_type":[32],"group":[271,318],"d_category":[1171],"genre":[1374],"class_list":["post-1679101","program","type-program","status-publish","format-standard","has-post-thumbnail","hentry","program_type-episode","group-travel","group-voyage","d_category-evasion","genre-entertainement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9pisode 14 - MyZen TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.myzen.tv\/fr\/program\/episode\/12848-episode-14-s00-e14\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9pisode 14 - MyZen TV\" \/>\n<meta property=\"og:description\" content=\"Des paysages naturels m\u00e9lang\u00e9s \u00e0 des sports extr\u00eames captur\u00e9s avec des cam\u00e9ras embarqu\u00e9es pour d\u00e9couvrir les plus beaux paysages de la plan\u00e8te.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myzen.tv\/fr\/program\/episode\/12848-episode-14-s00-e14\" \/>\n<meta property=\"og:site_name\" content=\"MyZen TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myzen.tv.fr\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T09:44:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/12\/la-terre-vue-du-sport-episode-1461c1b5f095045.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9pisode 14 - MyZen TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.myzen.tv\/fr\/program\/episode\/12848-episode-14-s00-e14\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9pisode 14 - MyZen TV","og_description":"Des paysages naturels m\u00e9lang\u00e9s \u00e0 des sports extr\u00eames captur\u00e9s avec des cam\u00e9ras embarqu\u00e9es pour d\u00e9couvrir les plus beaux paysages de la plan\u00e8te.","og_url":"https:\/\/www.myzen.tv\/fr\/program\/episode\/12848-episode-14-s00-e14","og_site_name":"MyZen TV","article_publisher":"https:\/\/www.facebook.com\/myzen.tv.fr\/","article_modified_time":"2026-04-28T09:44:32+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/12\/la-terre-vue-du-sport-episode-1461c1b5f095045.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/12848-episode-14-s00-e14","url":"https:\/\/www.myzen.tv\/fr\/program\/episode\/12848-episode-14-s00-e14","name":"\u00c9pisode 14 - MyZen TV","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/12848-episode-14-s00-e14#primaryimage"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/12848-episode-14-s00-e14#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/12\/la-terre-vue-du-sport-episode-1461c1b5f095045.jpeg","datePublished":"2021-12-21T11:09:36+00:00","dateModified":"2026-04-28T09:44:32+00:00","breadcrumb":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/12848-episode-14-s00-e14#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myzen.tv\/fr\/program\/episode\/12848-episode-14-s00-e14"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/12848-episode-14-s00-e14#primaryimage","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/12\/la-terre-vue-du-sport-episode-1461c1b5f095045.jpeg","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/12\/la-terre-vue-du-sport-episode-1461c1b5f095045.jpeg","width":1920,"height":1080,"caption":"Des paysages naturels m\u00e9lang\u00e9s \u00e0 des sports extr\u00eames captur\u00e9s avec des cam\u00e9ras embarqu\u00e9es pour d\u00e9couvrir les plus beaux paysages de la plan\u00e8te."},{"@type":"BreadcrumbList","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/12848-episode-14-s00-e14#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.myzen.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"Programs","item":"https:\/\/www.myzen.tv\/fr\/programs\/"},{"@type":"ListItem","position":3,"name":"\u00c9pisode 14"}]},{"@type":"WebSite","@id":"https:\/\/www.myzen.tv\/fr\/#website","url":"https:\/\/www.myzen.tv\/fr\/","name":"MyZen TV","description":"Your lifestyle and well-being channel","publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myzen.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.myzen.tv\/fr\/#organization","name":"MyZen TV","url":"https:\/\/www.myzen.tv\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","width":512,"height":512,"caption":"MyZen TV"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myzen.tv.fr\/","https:\/\/www.instagram.com\/myzentv\/"]}]}},"status_options":[{"label":"Inactive","value":"inactive"}],"_links":{"self":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/programs\/1679101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/programs"}],"about":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/types\/program"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media\/1679102"}],"wp:attachment":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media?parent=1679101"}],"wp:term":[{"taxonomy":"program_type","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/program_type?post=1679101"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/group?post=1679101"},{"taxonomy":"d_category","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/d_category?post=1679101"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/genre?post=1679101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}