{"id":1709271,"date":"2025-02-28T20:26:54","date_gmt":"2025-02-28T20:26:54","guid":{"rendered":"https:\/\/www.myzen.tv\/program\/\/14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06"},"modified":"2026-01-23T05:29:06","modified_gmt":"2026-01-23T05:29:06","slug":"14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06","status":"publish","type":"program","link":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06","title":{"rendered":"Salade de p\u00e2tes aux poivrons marin\u00e9s"},"content":{"rendered":"<p>Aujourd\u2019hui, nous pr\u00e9parons une salade de p\u00e2tes aux poivrons marin\u00e9s. Les p\u00e2tes, les tomates, les carottes et le parmesan sont associ\u00e9es \u00e0 des poivrons marin\u00e9s pour une touche acidul\u00e9e et parfum\u00e9e, des tomates et des jeunes pousses. Un assaisonnement \u00e0 l&rsquo;huile d&rsquo;olive, \u00e0 l&rsquo;ail et au romarin vient sublimer ce plat frais et gourmand.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd\u2019hui, nous pr\u00e9parons une salade de p\u00e2tes aux poivrons marin\u00e9s.<\/p>\n","protected":false},"featured_media":1710681,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"00:05:00","filesize":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","filesize_raw":""},"program_type":[32],"group":[261,314],"d_category":[1172],"genre":[1372],"class_list":["post-1709271","program","type-program","status-publish","format-standard","has-post-thumbnail","hentry","program_type-episode","group-cooking","group-cuisine","d_category-daily-wellbeing","genre-do-it-yourself"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Salade de p\u00e2tes aux poivrons marin\u00e9s - MyZen TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.myzen.tv\/fr\/program\/episode\/14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salade de p\u00e2tes aux poivrons marin\u00e9s - MyZen TV\" \/>\n<meta property=\"og:description\" content=\"Aujourd\u2019hui, nous pr\u00e9parons une salade de p\u00e2tes aux poivrons marin\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myzen.tv\/fr\/program\/episode\/14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06\" \/>\n<meta property=\"og:site_name\" content=\"MyZen TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myzen.tv.fr\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T05:29:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/02\/vegetarian-delights-saison-1-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines67c0c604e71bd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salade de p\u00e2tes aux poivrons marin\u00e9s - MyZen TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06\/","og_locale":"fr_FR","og_type":"article","og_title":"Salade de p\u00e2tes aux poivrons marin\u00e9s - MyZen TV","og_description":"Aujourd\u2019hui, nous pr\u00e9parons une salade de p\u00e2tes aux poivrons marin\u00e9s.","og_url":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06","og_site_name":"MyZen TV","article_publisher":"https:\/\/www.facebook.com\/myzen.tv.fr\/","article_modified_time":"2026-01-23T05:29:06+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/02\/vegetarian-delights-saison-1-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines67c0c604e71bd.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06","url":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06","name":"Salade de p\u00e2tes aux poivrons marin\u00e9s - MyZen TV","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06#primaryimage"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/02\/vegetarian-delights-saison-1-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines67c0c604e71bd.jpg","datePublished":"2025-02-28T20:26:54+00:00","dateModified":"2026-01-23T05:29:06+00:00","breadcrumb":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myzen.tv\/fr\/program\/episode\/14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06#primaryimage","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/02\/vegetarian-delights-saison-1-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines67c0c604e71bd.jpg","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/02\/vegetarian-delights-saison-1-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines67c0c604e71bd.jpg","width":1920,"height":1080,"caption":"Aujourd\u2019hui, nous pr\u00e9parons une salade savoureuse \u00e0 base de pommes de terre Kifferi et de poivrons marin\u00e9s."},{"@type":"BreadcrumbList","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14127-salade-avec-pommes-de-terre-kifferi-et-poivrons-marines-s-e06#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.myzen.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"Programs","item":"https:\/\/www.myzen.tv\/fr\/programs\/"},{"@type":"ListItem","position":3,"name":"Salade de p\u00e2tes aux poivrons marin\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.myzen.tv\/fr\/#website","url":"https:\/\/www.myzen.tv\/fr\/","name":"MyZen TV","description":"Your lifestyle and well-being channel","publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myzen.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.myzen.tv\/fr\/#organization","name":"MyZen TV","url":"https:\/\/www.myzen.tv\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","width":512,"height":512,"caption":"MyZen TV"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myzen.tv.fr\/","https:\/\/www.instagram.com\/myzentv\/"]}]}},"status_options":[{"label":"Inactive","value":"inactive"}],"_links":{"self":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/programs\/1709271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/programs"}],"about":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/types\/program"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media\/1710681"}],"wp:attachment":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media?parent=1709271"}],"wp:term":[{"taxonomy":"program_type","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/program_type?post=1709271"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/group?post=1709271"},{"taxonomy":"d_category","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/d_category?post=1709271"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/genre?post=1709271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}