{"id":1709279,"date":"2025-03-14T19:50:52","date_gmt":"2025-03-14T19:50:52","guid":{"rendered":"https:\/\/www.myzen.tv\/program\/\/14131-salade-de-legumes-grilles-s-e10"},"modified":"2026-01-23T05:29:42","modified_gmt":"2026-01-23T05:29:42","slug":"14131-salade-de-legumes-grilles-s-e10","status":"publish","type":"program","link":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14131-salade-de-legumes-grilles-s-e10","title":{"rendered":"Salade de l\u00e9gumes grill\u00e9s"},"content":{"rendered":"<p>Aujourd\u2019hui, nous pr\u00e9parons une salade de l\u00e9gumes grill\u00e9s, savoureuse et parfum\u00e9e. Les champignons de Paris, l\u2019aubergine, la courgette, l\u2019oignon rouge et la tomate sont r\u00f4tis avec du thym, du romarin frais et un filet d\u2019huile d\u2019olive. Des micropousses, de la roquette et de la laitue romaine apportent fra\u00eecheur et l\u00e9g\u00e8ret\u00e9. Le tout est relev\u00e9 par des c\u00e2pres, une touche de citron et un poivron marin\u00e9 \u00e0 l\u2019ail, au vinaigre et aux \u00e9pices pour une saveur intense et \u00e9quilibr\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd\u2019hui, nous pr\u00e9parons une salade de l\u00e9gumes grill\u00e9s, savoureuse et parfum\u00e9e. <\/p>\n","protected":false},"featured_media":1710689,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"00:05:00","filesize":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","filesize_raw":""},"program_type":[32],"group":[261,314],"d_category":[1172],"genre":[1372],"class_list":["post-1709279","program","type-program","status-publish","format-standard","has-post-thumbnail","hentry","program_type-episode","group-cooking","group-cuisine","d_category-daily-wellbeing","genre-do-it-yourself"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Salade de l\u00e9gumes grill\u00e9s - MyZen TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.myzen.tv\/fr\/program\/episode\/14131-salade-de-legumes-grilles-s-e10\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salade de l\u00e9gumes grill\u00e9s - MyZen TV\" \/>\n<meta property=\"og:description\" content=\"Aujourd\u2019hui, nous pr\u00e9parons une salade de l\u00e9gumes grill\u00e9s, savoureuse et parfum\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myzen.tv\/fr\/program\/episode\/14131-salade-de-legumes-grilles-s-e10\" \/>\n<meta property=\"og:site_name\" content=\"MyZen TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myzen.tv.fr\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T05:29:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/02\/vegetarian-delights-saison-1-salade-de-legumes-grilles67c0c61c1aff1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salade de l\u00e9gumes grill\u00e9s - MyZen TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14131-salade-de-legumes-grilles-s-e10\/","og_locale":"fr_FR","og_type":"article","og_title":"Salade de l\u00e9gumes grill\u00e9s - MyZen TV","og_description":"Aujourd\u2019hui, nous pr\u00e9parons une salade de l\u00e9gumes grill\u00e9s, savoureuse et parfum\u00e9e.","og_url":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14131-salade-de-legumes-grilles-s-e10","og_site_name":"MyZen TV","article_publisher":"https:\/\/www.facebook.com\/myzen.tv.fr\/","article_modified_time":"2026-01-23T05:29:42+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/02\/vegetarian-delights-saison-1-salade-de-legumes-grilles67c0c61c1aff1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14131-salade-de-legumes-grilles-s-e10","url":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14131-salade-de-legumes-grilles-s-e10","name":"Salade de l\u00e9gumes grill\u00e9s - MyZen TV","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14131-salade-de-legumes-grilles-s-e10#primaryimage"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14131-salade-de-legumes-grilles-s-e10#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/02\/vegetarian-delights-saison-1-salade-de-legumes-grilles67c0c61c1aff1.jpg","datePublished":"2025-03-14T19:50:52+00:00","dateModified":"2026-01-23T05:29:42+00:00","breadcrumb":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14131-salade-de-legumes-grilles-s-e10#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myzen.tv\/fr\/program\/episode\/14131-salade-de-legumes-grilles-s-e10"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14131-salade-de-legumes-grilles-s-e10#primaryimage","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/02\/vegetarian-delights-saison-1-salade-de-legumes-grilles67c0c61c1aff1.jpg","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/02\/vegetarian-delights-saison-1-salade-de-legumes-grilles67c0c61c1aff1.jpg","width":1920,"height":1080,"caption":"Aujourd\u2019hui, nous pr\u00e9parons une d\u00e9licieuse salade de l\u00e9gumes grill\u00e9s. Aubergines, courgettes, poivrons et tomates sont r\u00f4tis au four ou grill\u00e9s \u00e0 la po\u00eale pour r\u00e9v\u00e9ler toute leur saveur."},{"@type":"BreadcrumbList","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14131-salade-de-legumes-grilles-s-e10#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.myzen.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"Programs","item":"https:\/\/www.myzen.tv\/fr\/programs\/"},{"@type":"ListItem","position":3,"name":"Salade de l\u00e9gumes grill\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.myzen.tv\/fr\/#website","url":"https:\/\/www.myzen.tv\/fr\/","name":"MyZen TV","description":"Your lifestyle and well-being channel","publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myzen.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.myzen.tv\/fr\/#organization","name":"MyZen TV","url":"https:\/\/www.myzen.tv\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","width":512,"height":512,"caption":"MyZen TV"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myzen.tv.fr\/","https:\/\/www.instagram.com\/myzentv\/"]}]}},"status_options":[{"label":"Inactive","value":"inactive"}],"_links":{"self":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/programs\/1709279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/programs"}],"about":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/types\/program"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media\/1710689"}],"wp:attachment":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media?parent=1709279"}],"wp:term":[{"taxonomy":"program_type","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/program_type?post=1709279"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/group?post=1709279"},{"taxonomy":"d_category","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/d_category?post=1709279"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/genre?post=1709279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}