{"id":1709423,"date":"2026-04-14T20:45:22","date_gmt":"2026-04-14T20:45:22","guid":{"rendered":"https:\/\/www.myzen.tv\/program\/\/14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31"},"modified":"2026-04-14T20:45:22","modified_gmt":"2026-04-14T20:45:22","slug":"14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31","status":"publish","type":"program","link":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31","title":{"rendered":"Croquettes de Lentilles et de L\u00e9gumes"},"content":{"rendered":"<p>Aujourd\u2019hui, nous pr\u00e9parons des croquettes de lentilles et de l\u00e9gumes, une recette v\u00e9g\u00e9tarienne pleine de saveurs. Les lentilles sont m\u00e9lang\u00e9es avec de l&rsquo;oignon, des carottes, du c\u00e9leri-rave et des \u00e9pices comme le curry pour former une p\u00e2te qui est ensuite fa\u00e7onn\u00e9e en escalopes et dor\u00e9e \u00e0 l\u2019huile v\u00e9g\u00e9tale. Le poivron et les tomates cocktail ajoutent de la fra\u00eecheur et du go\u00fbt. La coriandre, le basilic et l&rsquo;aneth viennent parfumer le tout. Ces croquettes sont accompagn\u00e9es d\u2019une mayonnaise maison, faite d\u2019\u0153uf, de moutarde, d&rsquo;huile d&rsquo;olive, de citron et d\u2019un peu de sucre pour une touche de douceur. Un plat complet, savoureux et original !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd\u2019hui, nous pr\u00e9parons des croquettes de lentilles et de l\u00e9gumes, une recette v\u00e9g\u00e9tarienne pleine de saveurs.<\/p>\n","protected":false},"featured_media":1811839,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"00:05:00","filesize":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","filesize_raw":""},"program_type":[32],"group":[261],"d_category":[1172],"genre":[1372],"class_list":["post-1709423","program","type-program","status-publish","format-standard","has-post-thumbnail","hentry","program_type-episode","group-cooking","d_category-daily-wellbeing","genre-do-it-yourself"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Croquettes de Lentilles et de L\u00e9gumes - MyZen TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.myzen.tv\/fr\/program\/episode\/14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Croquettes de Lentilles et de L\u00e9gumes - MyZen TV\" \/>\n<meta property=\"og:description\" content=\"Aujourd\u2019hui, nous pr\u00e9parons des croquettes de lentilles et de l\u00e9gumes, une recette v\u00e9g\u00e9tarienne pleine de saveurs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myzen.tv\/fr\/program\/episode\/14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31\" \/>\n<meta property=\"og:site_name\" content=\"MyZen TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myzen.tv.fr\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/02\/vegetarian-delights-saison-1-nouilles-de-riz-aux-legumes67c0c648aeac6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Croquettes de Lentilles et de L\u00e9gumes - MyZen TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31\/","og_locale":"fr_FR","og_type":"article","og_title":"Croquettes de Lentilles et de L\u00e9gumes - MyZen TV","og_description":"Aujourd\u2019hui, nous pr\u00e9parons des croquettes de lentilles et de l\u00e9gumes, une recette v\u00e9g\u00e9tarienne pleine de saveurs.","og_url":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31","og_site_name":"MyZen TV","article_publisher":"https:\/\/www.facebook.com\/myzen.tv.fr\/","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/02\/vegetarian-delights-saison-1-nouilles-de-riz-aux-legumes67c0c648aeac6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31","url":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31","name":"Croquettes de Lentilles et de L\u00e9gumes - MyZen TV","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31#primaryimage"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2026\/04\/vegetarian-delights-saison-1-croquettes-de-lentilles-et-de-legumes69dea742a5d2d.jpeg","datePublished":"2026-04-14T20:45:22+00:00","dateModified":"2026-04-14T20:45:22+00:00","breadcrumb":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myzen.tv\/fr\/program\/episode\/14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31#primaryimage","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2026\/04\/vegetarian-delights-saison-1-croquettes-de-lentilles-et-de-legumes69dea742a5d2d.jpeg","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2026\/04\/vegetarian-delights-saison-1-croquettes-de-lentilles-et-de-legumes69dea742a5d2d.jpeg","width":1920,"height":1080,"caption":"Aujourd\u2019hui, nous pr\u00e9parons des croquettes de lentilles et de l\u00e9gumes, une recette v\u00e9g\u00e9tarienne pleine de saveurs."},{"@type":"BreadcrumbList","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14102-croquettes-de-lentilles-avec-legumes-et-herbes-s-e31#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.myzen.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"Programs","item":"https:\/\/www.myzen.tv\/fr\/programs\/"},{"@type":"ListItem","position":3,"name":"Croquettes de Lentilles et de L\u00e9gumes"}]},{"@type":"WebSite","@id":"https:\/\/www.myzen.tv\/fr\/#website","url":"https:\/\/www.myzen.tv\/fr\/","name":"MyZen TV","description":"Your lifestyle and well-being channel","publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myzen.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.myzen.tv\/fr\/#organization","name":"MyZen TV","url":"https:\/\/www.myzen.tv\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","width":512,"height":512,"caption":"MyZen TV"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myzen.tv.fr\/","https:\/\/www.instagram.com\/myzentv\/"]}]}},"status_options":[{"label":"Inactive","value":"inactive"}],"_links":{"self":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/programs\/1709423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/programs"}],"about":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/types\/program"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media\/1811839"}],"wp:attachment":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media?parent=1709423"}],"wp:term":[{"taxonomy":"program_type","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/program_type?post=1709423"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/group?post=1709423"},{"taxonomy":"d_category","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/d_category?post=1709423"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/genre?post=1709423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}