{"id":1745380,"date":"2025-10-30T05:05:37","date_gmt":"2025-10-30T05:05:37","guid":{"rendered":"https:\/\/www.myzen.tv\/?post_type=program&#038;p=1745380"},"modified":"2026-05-11T23:03:17","modified_gmt":"2026-05-11T23:03:17","slug":"14509-episode-4-s-e04","status":"publish","type":"program","link":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14509-episode-4-s-e04","title":{"rendered":"\u00c9pisode 4"},"content":{"rendered":"<p>Rien ne symbolise mieux le bien-toilett\u00e9 qu\u2019un caniche standard, un bichon ou un Bedlington terrier. Aujourd\u2019hui, les toiletteurs devront donner un look chic et classe \u00e0 leur chien. Les trois \u00e9quipes les moins bonnes s\u2019affronteront ensuite dans une \u00e9preuve d\u2019\u00e9limination plac\u00e9e sous le signe du punk, avec la juge invit\u00e9e Nicky Renwood, experte de Melbourne. Ce d\u00e9fi exige de l\u2019attitude.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Du glamour sophistiqu\u00e9 aux cr\u00eates et couleurs rebelles, les toiletteurs jouent sur tous les styles. Entre \u00e9l\u00e9gance et rock\u2019n\u2019roll, qui ma\u00eetrisera cette double facette pour rester dans la course ?<\/p>\n","protected":false},"featured_media":1772979,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"00:55:00","filesize":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","filesize_raw":""},"program_type":[32],"group":[],"d_category":[],"genre":[1383],"class_list":["post-1745380","program","type-program","status-publish","format-standard","has-post-thumbnail","hentry","program_type-episode","genre-reality-show"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9pisode 4 - MyZen TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.myzen.tv\/fr\/program\/episode\/14509-episode-4-s-e04\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9pisode 4 - MyZen TV\" \/>\n<meta property=\"og:description\" content=\"Du glamour sophistiqu\u00e9 aux cr\u00eates et couleurs rebelles, les toiletteurs jouent sur tous les styles. Entre \u00e9l\u00e9gance et rock\u2019n\u2019roll, qui ma\u00eetrisera cette double facette pour rester dans la course ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myzen.tv\/fr\/program\/episode\/14509-episode-4-s-e04\" \/>\n<meta property=\"og:site_name\" content=\"MyZen TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myzen.tv.fr\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T23:03:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/10\/chiens-parfaits-la-competition-ultime-australie-saison-1-episode-46902f221b9db4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"627\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9pisode 4 - MyZen TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14509-episode-4-s-e04\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9pisode 4 - MyZen TV","og_description":"Du glamour sophistiqu\u00e9 aux cr\u00eates et couleurs rebelles, les toiletteurs jouent sur tous les styles. Entre \u00e9l\u00e9gance et rock\u2019n\u2019roll, qui ma\u00eetrisera cette double facette pour rester dans la course ?","og_url":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14509-episode-4-s-e04","og_site_name":"MyZen TV","article_publisher":"https:\/\/www.facebook.com\/myzen.tv.fr\/","article_modified_time":"2026-05-11T23:03:17+00:00","og_image":[{"width":627,"height":470,"url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/10\/chiens-parfaits-la-competition-ultime-australie-saison-1-episode-46902f221b9db4.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14509-episode-4-s-e04","url":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14509-episode-4-s-e04","name":"\u00c9pisode 4 - MyZen TV","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14509-episode-4-s-e04#primaryimage"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14509-episode-4-s-e04#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/10\/chiens-parfaits-la-competition-ultime-australie-saison-1-episode-46902f221b9db4.png","datePublished":"2025-10-30T05:05:37+00:00","dateModified":"2026-05-11T23:03:17+00:00","breadcrumb":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14509-episode-4-s-e04#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myzen.tv\/fr\/program\/episode\/14509-episode-4-s-e04"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14509-episode-4-s-e04#primaryimage","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/10\/chiens-parfaits-la-competition-ultime-australie-saison-1-episode-46902f221b9db4.png","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/10\/chiens-parfaits-la-competition-ultime-australie-saison-1-episode-46902f221b9db4.png","width":627,"height":470,"caption":"Du glamour sophistiqu\u00e9 aux cr\u00eates et couleurs rebelles, les toiletteurs jouent sur tous les styles. Entre \u00e9l\u00e9gance et rock\u2019n\u2019roll, qui ma\u00eetrisera cette double facette pour rester dans la course ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14509-episode-4-s-e04#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.myzen.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"Programs","item":"https:\/\/www.myzen.tv\/fr\/programs\/"},{"@type":"ListItem","position":3,"name":"\u00c9pisode 4"}]},{"@type":"WebSite","@id":"https:\/\/www.myzen.tv\/fr\/#website","url":"https:\/\/www.myzen.tv\/fr\/","name":"MyZen TV","description":"Your lifestyle and well-being channel","publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myzen.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.myzen.tv\/fr\/#organization","name":"MyZen TV","url":"https:\/\/www.myzen.tv\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","width":512,"height":512,"caption":"MyZen TV"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myzen.tv.fr\/","https:\/\/www.instagram.com\/myzentv\/"]}]}},"status_options":[{"label":"Inactive","value":"inactive"}],"_links":{"self":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/programs\/1745380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/programs"}],"about":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/types\/program"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media\/1772979"}],"wp:attachment":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media?parent=1745380"}],"wp:term":[{"taxonomy":"program_type","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/program_type?post=1745380"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/group?post=1745380"},{"taxonomy":"d_category","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/d_category?post=1745380"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/genre?post=1745380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}