{"id":1745384,"date":"2025-10-30T05:05:41","date_gmt":"2025-10-30T05:05:41","guid":{"rendered":"https:\/\/www.myzen.tv\/?post_type=program&#038;p=1745384"},"modified":"2026-05-11T23:03:22","modified_gmt":"2026-05-11T23:03:22","slug":"14511-episode-6-s-e06","status":"publish","type":"program","link":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14511-episode-6-s-e06","title":{"rendered":"\u00c9pisode 6"},"content":{"rendered":"<p>Les contes de f\u00e9es \u00e9veillent la cr\u00e9ativit\u00e9. Les comp\u00e9titeurs seront transport\u00e9s dans un autre monde o\u00f9 ils devront imaginer le meilleur prince, princesse, ou m\u00eame citrouille ! Pour cet \u00e9pisode d\u00e9licat, le juge invit\u00e9 est Joey Villani, \u00ab Le Parrain \u00bb du toilettage canin, venu sp\u00e9cialement du New Jersey. Sa voix de baryton sera parfaite pour le d\u00e9fi d\u2019\u00e9limination inspir\u00e9 de la barbe \u00e0 papa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les poils se transforment en princes, princesses, citrouilles ou cr\u00e9atures f\u00e9eriques dans un festival de douceur et de magie. Un juge l\u00e9gendaire impose son verdict dans ce duel haut en couleurs et en paillettes !<\/p>\n","protected":false},"featured_media":1772981,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"00:55:00","filesize":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","filesize_raw":""},"program_type":[32],"group":[],"d_category":[],"genre":[1383],"class_list":["post-1745384","program","type-program","status-publish","format-standard","has-post-thumbnail","hentry","program_type-episode","genre-reality-show"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9pisode 6 - MyZen TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.myzen.tv\/fr\/program\/episode\/14511-episode-6-s-e06\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9pisode 6 - MyZen TV\" \/>\n<meta property=\"og:description\" content=\"Les poils se transforment en princes, princesses, citrouilles ou cr\u00e9atures f\u00e9eriques dans un festival de douceur et de magie. Un juge l\u00e9gendaire impose son verdict dans ce duel haut en couleurs et en paillettes !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myzen.tv\/fr\/program\/episode\/14511-episode-6-s-e06\" \/>\n<meta property=\"og:site_name\" content=\"MyZen TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myzen.tv.fr\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T23:03:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/10\/chiens-parfaits-la-competition-ultime-australie-saison-1-episode-66902f225b4f02-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9pisode 6 - MyZen TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14511-episode-6-s-e06\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9pisode 6 - MyZen TV","og_description":"Les poils se transforment en princes, princesses, citrouilles ou cr\u00e9atures f\u00e9eriques dans un festival de douceur et de magie. Un juge l\u00e9gendaire impose son verdict dans ce duel haut en couleurs et en paillettes !","og_url":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14511-episode-6-s-e06","og_site_name":"MyZen TV","article_publisher":"https:\/\/www.facebook.com\/myzen.tv.fr\/","article_modified_time":"2026-05-11T23:03:22+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/10\/chiens-parfaits-la-competition-ultime-australie-saison-1-episode-66902f225b4f02-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14511-episode-6-s-e06","url":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14511-episode-6-s-e06","name":"\u00c9pisode 6 - MyZen TV","isPartOf":{"@id":"https:\/\/www.myzen.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14511-episode-6-s-e06#primaryimage"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14511-episode-6-s-e06#primaryimage"},"thumbnailUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/10\/chiens-parfaits-la-competition-ultime-australie-saison-1-episode-66902f225b4f02-scaled.jpg","datePublished":"2025-10-30T05:05:41+00:00","dateModified":"2026-05-11T23:03:22+00:00","breadcrumb":{"@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14511-episode-6-s-e06#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myzen.tv\/fr\/program\/episode\/14511-episode-6-s-e06"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14511-episode-6-s-e06#primaryimage","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/10\/chiens-parfaits-la-competition-ultime-australie-saison-1-episode-66902f225b4f02-scaled.jpg","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2025\/10\/chiens-parfaits-la-competition-ultime-australie-saison-1-episode-66902f225b4f02-scaled.jpg","width":2560,"height":1707,"caption":"Les poils se transforment en princes, princesses, citrouilles ou cr\u00e9atures f\u00e9eriques dans un festival de douceur et de magie. Un juge l\u00e9gendaire impose son verdict dans ce duel haut en couleurs et en paillettes !"},{"@type":"BreadcrumbList","@id":"https:\/\/www.myzen.tv\/fr\/program\/episode\/14511-episode-6-s-e06#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.myzen.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"Programs","item":"https:\/\/www.myzen.tv\/fr\/programs\/"},{"@type":"ListItem","position":3,"name":"\u00c9pisode 6"}]},{"@type":"WebSite","@id":"https:\/\/www.myzen.tv\/fr\/#website","url":"https:\/\/www.myzen.tv\/fr\/","name":"MyZen TV","description":"Your lifestyle and well-being channel","publisher":{"@id":"https:\/\/www.myzen.tv\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myzen.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.myzen.tv\/fr\/#organization","name":"MyZen TV","url":"https:\/\/www.myzen.tv\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","contentUrl":"https:\/\/www.myzen.tv\/wp-content\/uploads\/2021\/05\/cropped-ICON_MZtv-LOGO_firetv640-1-1.png","width":512,"height":512,"caption":"MyZen TV"},"image":{"@id":"https:\/\/www.myzen.tv\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myzen.tv.fr\/","https:\/\/www.instagram.com\/myzentv\/"]}]}},"status_options":[{"label":"Inactive","value":"inactive"}],"_links":{"self":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/programs\/1745384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/programs"}],"about":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/types\/program"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media\/1772981"}],"wp:attachment":[{"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/media?parent=1745384"}],"wp:term":[{"taxonomy":"program_type","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/program_type?post=1745384"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/group?post=1745384"},{"taxonomy":"d_category","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/d_category?post=1745384"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.myzen.tv\/fr\/wp-json\/wp\/v2\/genre?post=1745384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}